{"id":133,"date":"2009-05-11T11:37:03","date_gmt":"2009-05-11T09:37:03","guid":{"rendered":"http:\/\/www.elternforen.com\/Blog\/?p=133"},"modified":"2009-05-11T12:22:40","modified_gmt":"2009-05-11T10:22:40","slug":"kunstliche-befruchtung-%e2%80%93-wieviele-embryos-sind-erlaubt-133","status":"publish","type":"post","link":"https:\/\/www.elternforen.com\/Blog\/kunstliche-befruchtung-%e2%80%93-wieviele-embryos-sind-erlaubt-133\/","title":{"rendered":"K\u00fcnstliche Befruchtung \u2013 wieviele Embryos sind erlaubt?"},"content":{"rendered":"ANZEIGE - <p style=\"text-align: left;\">Nachdem eine Frau im Januar 2009 Achtlinge in den USA geboren hatte, l\u00f6ste sie weltweit eine hitzige Diskussion aus. In den USA gibt es keine Begrenzungen f\u00fcr das Einpflanzen von <a title=\"Embryonen\" href=\"http:\/\/www.elternforen.com\/Lexikon\/Embryo.htm\" target=\"_blank\">Embryonen<\/a>. Die nun insgesamt vierzehnfache Mutter hat all ihre Kinder durch <a title=\"k\u00fcnstliche Befruchtung\" href=\"http:\/\/www.elternforen.com\/Fachinformationen\/Bericht_IVF.htm\" target=\"_blank\">k\u00fcnstliche Befruchtung<\/a> bekommen. Mittlerweile ist nun auch der kleinste und schw\u00e4chste der Achtlinge, Jonah Angel, aus dem Krankenhaus entlassen worden. Die 33-j\u00e4hrige Mutter lebt jetzt mit ihren Kindern in einem Vorort von Los Angeles.<\/p>\n<p>Nach einer Studie finnischer Wissenschaftler an der Universit\u00e4t Oulu scheint das Einpflanzen eines Embryos Erfolg versprechender zu sein, als der Versuch mit mehreren <a title=\"Eizellen\" href=\"http:\/\/www.elternforen.com\/Lexikon\/Eizelle.htm\">Eizellen<\/a>. Zudem ist auch das Einbringen eines Embryos f\u00fcr die Gesundheit der Mutter weniger gef\u00e4hrlich. Die Forscher gehen \u00fcbrigens davon aus, dass der Erfolg einer <a href=\"http:\/\/www.gesundheitsspiegel.de\/?p=111\" rel=\"nofollow\" target=\"_blank\">k\u00fcnstlichen Befruchtung<\/a> nicht vom Alter der Mutter, sondern von der Qualit\u00e4t des eingepflanzten Embryos abh\u00e4nge.<\/p>\n<p>Mehrlingsgeburten sind \u00e4u\u00dferst umstritten, da sie die Gesundheit der Mutter erheblich gef\u00e4hrden und Entwicklungsst\u00f6rungen der Kinder die Folge sein k\u00f6nnen. Daher ist in vielen L\u00e4ndern gesetzlich geregelt, wieviele Embryonen Frauen h\u00f6chstens eingepflanzt werden d\u00fcrfen. Derzeit ist es nach dem Embryonengesetz in Deutschland so geregelt, dass innerhalb eines Zyklus maximal drei Embryonen eingepflanzt werden d\u00fcrfen.<\/p>\n<p>In Skandinavien sieht die Situation etwas anders aus. F\u00fcr Frauen bis 35 Jahren gilt in skandinavischen L\u00e4ndern als Standardmethode der In-vitro-Fertilisation der <a href=\"http:\/\/www.baby-blog.de\/index.php\/2005\/10\/06\/polkorperdiagnostik\" rel=\"nofollow\" target=\"_blank\">Single-Embryo-Transfer<\/a>. Die \u00c4rzte setzen also der zuk\u00fcnftigen Mutter nach der Befruchtung im Labor nur einen Embryo ein. Es wird der Embryo mit den besten Chancen und der h\u00f6chsten Qualit\u00e4t ausgew\u00e4hlt. Auf diese Weise wird die Erfolgsquote erh\u00f6ht, ohne die Frau dem erh\u00f6hten Risiko einer <a title=\"Mehrlingsschwangerschaft\" href=\"http:\/\/www.elternforen.com\/Fachinformationen\/Zwillinge.htm\">Mehrlingsschwangerschaft<\/a> auszusetzen.<\/p>\n<p>In Deutschland wird diese selektive Vorauswahl durch das geltende <a href=\"http:\/\/hopewithivf.wordpress.com\/2007\/07\/11\/embryonenschutzgesetz-totet-feten\/\" rel=\"nofollow\" target=\"_blank\">Embryonenschutzgesetz<\/a> verboten. Hier d\u00fcrfen nur so viele befruchtete Eizellen, die \u00fcber das sogenannte Vorkernstadium hinausgehen, im Labor kultiviert werden, wie dann auch sp\u00e4ter in die Geb\u00e4rmutter der Frau eingepflanzt werden. Derzeit sind dies maximal drei Embryonen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANZEIGE &#8211; Nachdem eine Frau im Januar 2009 Achtlinge in den USA geboren hatte, l\u00f6ste sie weltweit eine hitzige Diskussion aus. In den USA gibt es keine Begrenzungen f\u00fcr das Einpflanzen von Embryonen. Die nun insgesamt vierzehnfache Mutter hat all ihre Kinder durch k\u00fcnstliche Befruchtung bekommen. Mittlerweile ist nun auch der kleinste und schw\u00e4chste der [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-133","post","type-post","status-publish","format-standard","hentry","category-schwangerschaft"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>K\u00fcnstliche Befruchtung \u2013 wieviele Embryos sind erlaubt? - elternforen.com - Ratgeber-Magazin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elternforen.com\/Blog\/kunstliche-befruchtung-\u2013-wieviele-embryos-sind-erlaubt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"K\u00fcnstliche Befruchtung \u2013 wieviele Embryos sind erlaubt? - elternforen.com - Ratgeber-Magazin\" \/>\n<meta property=\"og:description\" content=\"ANZEIGE - Nachdem eine Frau im Januar 2009 Achtlinge in den USA geboren hatte, l\u00f6ste sie weltweit eine hitzige Diskussion aus. In den USA gibt es keine Begrenzungen f\u00fcr das Einpflanzen von Embryonen. Die nun insgesamt vierzehnfache Mutter hat all ihre Kinder durch k\u00fcnstliche Befruchtung bekommen. Mittlerweile ist nun auch der kleinste und schw\u00e4chste der [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elternforen.com\/Blog\/kunstliche-befruchtung-\u2013-wieviele-embryos-sind-erlaubt\/\" \/>\n<meta property=\"og:site_name\" content=\"elternforen.com - Ratgeber-Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2009-05-11T09:37:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2009-05-11T10:22:40+00:00\" \/>\n<meta name=\"author\" content=\"Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/kunstliche-befruchtung-%e2%80%93-wieviele-embryos-sind-erlaubt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/kunstliche-befruchtung-%e2%80%93-wieviele-embryos-sind-erlaubt\\\/\"},\"author\":{\"name\":\"Redaktion\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#\\\/schema\\\/person\\\/ed54c95f56854d06c00044b7c064dfba\"},\"headline\":\"K\u00fcnstliche Befruchtung \u2013 wieviele Embryos sind erlaubt?\",\"datePublished\":\"2009-05-11T09:37:03+00:00\",\"dateModified\":\"2009-05-11T10:22:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/kunstliche-befruchtung-%e2%80%93-wieviele-embryos-sind-erlaubt\\\/\"},\"wordCount\":340,\"articleSection\":[\"Schwangerschaft\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/kunstliche-befruchtung-%e2%80%93-wieviele-embryos-sind-erlaubt\\\/\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/kunstliche-befruchtung-%e2%80%93-wieviele-embryos-sind-erlaubt\\\/\",\"name\":\"K\u00fcnstliche Befruchtung \u2013 wieviele Embryos sind erlaubt? - elternforen.com - Ratgeber-Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#website\"},\"datePublished\":\"2009-05-11T09:37:03+00:00\",\"dateModified\":\"2009-05-11T10:22:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#\\\/schema\\\/person\\\/ed54c95f56854d06c00044b7c064dfba\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/kunstliche-befruchtung-%e2%80%93-wieviele-embryos-sind-erlaubt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/kunstliche-befruchtung-%e2%80%93-wieviele-embryos-sind-erlaubt\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/kunstliche-befruchtung-%e2%80%93-wieviele-embryos-sind-erlaubt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"K\u00c3\u00bcnstliche Befruchtung \u00c3\u00a2\u00e2\u201a\u00ac\u00e2\u20ac\u0153 wieviele Embryos sind erlaubt?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#website\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/\",\"name\":\"elternforen.com - Ratgeber-Magazin\",\"description\":\"Der Blog \u00fcber Familie, Schwangerschaft, Babys und Kinder\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#\\\/schema\\\/person\\\/ed54c95f56854d06c00044b7c064dfba\",\"name\":\"Redaktion\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"K\u00fcnstliche Befruchtung \u2013 wieviele Embryos sind erlaubt? - elternforen.com - Ratgeber-Magazin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elternforen.com\/Blog\/kunstliche-befruchtung-\u2013-wieviele-embryos-sind-erlaubt\/","og_locale":"de_DE","og_type":"article","og_title":"K\u00fcnstliche Befruchtung \u2013 wieviele Embryos sind erlaubt? - elternforen.com - Ratgeber-Magazin","og_description":"ANZEIGE - Nachdem eine Frau im Januar 2009 Achtlinge in den USA geboren hatte, l\u00f6ste sie weltweit eine hitzige Diskussion aus. In den USA gibt es keine Begrenzungen f\u00fcr das Einpflanzen von Embryonen. Die nun insgesamt vierzehnfache Mutter hat all ihre Kinder durch k\u00fcnstliche Befruchtung bekommen. Mittlerweile ist nun auch der kleinste und schw\u00e4chste der [&hellip;]","og_url":"https:\/\/www.elternforen.com\/Blog\/kunstliche-befruchtung-\u2013-wieviele-embryos-sind-erlaubt\/","og_site_name":"elternforen.com - Ratgeber-Magazin","article_published_time":"2009-05-11T09:37:03+00:00","article_modified_time":"2009-05-11T10:22:40+00:00","author":"Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Redaktion","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.elternforen.com\/Blog\/kunstliche-befruchtung-%e2%80%93-wieviele-embryos-sind-erlaubt\/#article","isPartOf":{"@id":"https:\/\/www.elternforen.com\/Blog\/kunstliche-befruchtung-%e2%80%93-wieviele-embryos-sind-erlaubt\/"},"author":{"name":"Redaktion","@id":"https:\/\/www.elternforen.com\/Blog\/#\/schema\/person\/ed54c95f56854d06c00044b7c064dfba"},"headline":"K\u00fcnstliche Befruchtung \u2013 wieviele Embryos sind erlaubt?","datePublished":"2009-05-11T09:37:03+00:00","dateModified":"2009-05-11T10:22:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.elternforen.com\/Blog\/kunstliche-befruchtung-%e2%80%93-wieviele-embryos-sind-erlaubt\/"},"wordCount":340,"articleSection":["Schwangerschaft"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.elternforen.com\/Blog\/kunstliche-befruchtung-%e2%80%93-wieviele-embryos-sind-erlaubt\/","url":"https:\/\/www.elternforen.com\/Blog\/kunstliche-befruchtung-%e2%80%93-wieviele-embryos-sind-erlaubt\/","name":"K\u00fcnstliche Befruchtung \u2013 wieviele Embryos sind erlaubt? - elternforen.com - Ratgeber-Magazin","isPartOf":{"@id":"https:\/\/www.elternforen.com\/Blog\/#website"},"datePublished":"2009-05-11T09:37:03+00:00","dateModified":"2009-05-11T10:22:40+00:00","author":{"@id":"https:\/\/www.elternforen.com\/Blog\/#\/schema\/person\/ed54c95f56854d06c00044b7c064dfba"},"breadcrumb":{"@id":"https:\/\/www.elternforen.com\/Blog\/kunstliche-befruchtung-%e2%80%93-wieviele-embryos-sind-erlaubt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elternforen.com\/Blog\/kunstliche-befruchtung-%e2%80%93-wieviele-embryos-sind-erlaubt\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.elternforen.com\/Blog\/kunstliche-befruchtung-%e2%80%93-wieviele-embryos-sind-erlaubt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elternforen.com\/Blog\/"},{"@type":"ListItem","position":2,"name":"K\u00c3\u00bcnstliche Befruchtung \u00c3\u00a2\u00e2\u201a\u00ac\u00e2\u20ac\u0153 wieviele Embryos sind erlaubt?"}]},{"@type":"WebSite","@id":"https:\/\/www.elternforen.com\/Blog\/#website","url":"https:\/\/www.elternforen.com\/Blog\/","name":"elternforen.com - Ratgeber-Magazin","description":"Der Blog \u00fcber Familie, Schwangerschaft, Babys und Kinder","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elternforen.com\/Blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.elternforen.com\/Blog\/#\/schema\/person\/ed54c95f56854d06c00044b7c064dfba","name":"Redaktion","url":"https:\/\/www.elternforen.com\/Blog\/author\/redaktion\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts\/133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/comments?post=133"}],"version-history":[{"count":3,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts\/133\/revisions"}],"predecessor-version":[{"id":171,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts\/133\/revisions\/171"}],"wp:attachment":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/media?parent=133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/categories?post=133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/tags?post=133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}