{"id":1539,"date":"2013-12-10T10:12:03","date_gmt":"2013-12-10T09:12:03","guid":{"rendered":"http:\/\/www.elternforen.com\/Blog\/?p=1539"},"modified":"2022-09-16T11:03:08","modified_gmt":"2022-09-16T09:03:08","slug":"eileiterschwangerschaft-1539","status":"publish","type":"post","link":"https:\/\/www.elternforen.com\/Blog\/eileiterschwangerschaft-1539\/","title":{"rendered":"Eileiterschwangerschaft"},"content":{"rendered":"ANZEIGE - <p>Die Eileiterschwangerschaft ist eine Schwangerschaft au\u00dferhalb der Geb\u00e4rmutter und kommt den offiziellen Zahlen nach, bei 1-2 % der Schwangeren vor. Oft enden viele Eileiterschwangerschaften v\u00f6llig unbemerkt durch eine Fehlgeburt. Zur Fehlgeburt kommt es meistens schon im sehr fr\u00fchen Stadium der Schwangerschaft. Bei einer sogenannten Eileiterschwangerschaft nistet sich das Ei nicht in der Geb\u00e4rmutter ein, sondern in der Schleimhaut des Eileiters. Ursachen daf\u00fcr k\u00f6nnen funktionelle St\u00f6rungen sein.<\/p>\n<p><strong>Symptome einer Eileiterschwangerschaft<\/strong><\/p>\n<p>Die Symptome k\u00f6nnen durchaus denen einer normalen Schwangerschaft gleichen. Die Periode bleibt aus, Harndrang, Spannungsschmerz in der Brust und \u00dcbelkeit. Zudem f\u00e4llt ein Schwangerschaftstest positiv aus. Meistens setzen in der 6. bis 9. Woche auch die Unterleibschmerzen ein. Dabei kann es unter anderem zu Schmierblutungen f\u00fchren. Alarmierende Anzeichen sind sowohl Ohnmachtsanf\u00e4lle, erh\u00f6hte Temperatur, als auch ein allgemeines Unwohlsein. Bei diesen Anzeichen sollten unbedingt ein Arzt aufgesucht werden.<\/p>\n<p><strong>Diagnose: Eileiterschwangerschaft<\/strong><\/p>\n<p>Der Verlauf einer <a title=\"Eileiterschwangerschaft\" href=\"http:\/\/www.mamiweb.de\/familie\/eileiterschwangerschaft-tubargraviditaet\/1\" target=\"_blank\" rel=\"noopener\">Eileiterschwangerschaft<\/a> ist unterschiedlich. Eine genaue Diagnose kann erst nach einer Untersuchung durch einen Arzt festgestellt werden. Da die Symptome auch auf andere Diagnosen passen, ist eine \u00e4rztliche Untersuchung unumg\u00e4nglich. Wird eine Eileiterschwangerschaft zu sp\u00e4t festgestellt, kann das zu einem Riss im Eileiter f\u00fchren. F\u00fcr die betroffene Frau kann das lebensbedrohliche Konsequenzen haben.<br \/>\nBei der Diagnose hat es kein Gyn\u00e4kologe leicht, denn eine Eileiterschwangerschaft ist im Anfangsstadium nur sehr schwer auf dem Ultraschall zu erkennen. Wenn sp\u00e4testens in der 6. Schwangerschaftswoche nichts auf dem Ultraschall zu erkennen ist, handelt es sich im Normalfall, um eine Schwangerschaft au\u00dferhalb der Geb\u00e4rmutter. Durch eine Vaginalsonografie kann der Arzt diagnostizieren, ob eine Schwangerschaft in der Geb\u00e4rmutterh\u00f6hle besteht.<br \/>\nKann eine derartige Schwangerschaft ausgeschlossen werden, muss die Geb\u00e4rmutter der Frau mit anderen Untersuchungsmethoden kontrolliert werden.<\/p>\n<p><strong>Behandlung bei einer Eileiterschwangerschaft<\/strong><\/p>\n<p>Wichtig ist es, dass die Eileiterschwangerschaft so fr\u00fch wie m\u00f6glich entdeckt wird. Dadurch werden schlimme Folgen f\u00fcr die betroffene Frau verhindert, wie zum Beispiel das Entfernen der Eileiter.<br \/>\nBleiben die Werte der Schwangerschaftshormone unten und gering, dann ist die Chance einer <a href=\"http:\/\/www.elternforen.com\/Fachinformationen\/Fehlgeburt.htm\" rel=\"nofollow\">nat\u00fcrlichen Fehlgeburt<\/a> hoch und hinterl\u00e4sst keine gro\u00dfen R\u00fcckst\u00e4nde. Dabei wird endoskopisch mit einer Bauchspiegelung der Eileiter ge\u00f6ffnet und das in der Schleimhaut eingenistete Embryo entfernt. Nach der Operation verheilt der Eileiter ohne bleibende Sch\u00e4den. Trotzdem muss sich nach einer solchen Schwangerschaft, auf eine erneute Eileiterschwangerschaft eingestellt werden. Wenn der Arzt die Diagnose zu sp\u00e4t gestellt hat, k\u00f6nnen starke Verwachsungen vorliegen. In diesem Fall muss anschlie\u00dfend der gesamte Eileiter entfernt werden, zum Gl\u00fcck kommt das nur sehr selten vor. Bei der Eileiterentfernung wird das komplette Gewebe abgenommen, welches w\u00e4hrend der Schwangerschaft entstanden ist. Kann bei der ersten Operation nicht das gesamte Gewebe entfernt werden, ist eine zweite Operation n\u00f6tig. Eine spezielle Therapie, mit dem Stoff Methotrexat, wird dabei angewendet. Dieses Zellgift sorgt daf\u00fcr, das sich jegliches Gewebe zersetzt.<\/p>\n<p><strong>Erneute Schwangerschaft<\/strong><\/p>\n<p>Nach einer Eileiterschwangerschaft braucht der K\u00f6rper mindestens 3 Monate, damit das Gewebe vollst\u00e4ndig heilt. Allerdings wird bei einer Behandlung mit dem Zellgift Methotrexat, eine Heilungszeit von mindestens 6 Monaten ben\u00f6tigt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANZEIGE &#8211; Die Eileiterschwangerschaft ist eine Schwangerschaft au\u00dferhalb der Geb\u00e4rmutter und kommt den offiziellen Zahlen nach, bei 1-2 % der Schwangeren vor. Oft enden viele Eileiterschwangerschaften v\u00f6llig unbemerkt durch eine Fehlgeburt. Zur Fehlgeburt kommt es meistens schon im sehr fr\u00fchen Stadium der Schwangerschaft. Bei einer sogenannten Eileiterschwangerschaft nistet sich das Ei nicht in der Geb\u00e4rmutter [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":9177,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[337],"class_list":["post-1539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schwangerschaft","tag-eileiterschwangerschaft"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eileiterschwangerschaft - elternforen.com - Ratgeber-Magazin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elternforen.com\/Blog\/eileiterschwangerschaft-1539\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eileiterschwangerschaft - elternforen.com - Ratgeber-Magazin\" \/>\n<meta property=\"og:description\" content=\"ANZEIGE - Die Eileiterschwangerschaft ist eine Schwangerschaft au\u00dferhalb der Geb\u00e4rmutter und kommt den offiziellen Zahlen nach, bei 1-2 % der Schwangeren vor. Oft enden viele Eileiterschwangerschaften v\u00f6llig unbemerkt durch eine Fehlgeburt. Zur Fehlgeburt kommt es meistens schon im sehr fr\u00fchen Stadium der Schwangerschaft. Bei einer sogenannten Eileiterschwangerschaft nistet sich das Ei nicht in der Geb\u00e4rmutter [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elternforen.com\/Blog\/eileiterschwangerschaft-1539\/\" \/>\n<meta property=\"og:site_name\" content=\"elternforen.com - Ratgeber-Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2013-12-10T09:12:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-16T09:03:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2013\/02\/pregnant-6189040_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/eileiterschwangerschaft-1539\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/eileiterschwangerschaft-1539\\\/\"},\"author\":{\"name\":\"Redaktion\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#\\\/schema\\\/person\\\/ed54c95f56854d06c00044b7c064dfba\"},\"headline\":\"Eileiterschwangerschaft\",\"datePublished\":\"2013-12-10T09:12:03+00:00\",\"dateModified\":\"2022-09-16T09:03:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/eileiterschwangerschaft-1539\\\/\"},\"wordCount\":512,\"image\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/eileiterschwangerschaft-1539\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/pregnant-6189040_1920.jpg\",\"keywords\":[\"Eileiterschwangerschaft\"],\"articleSection\":[\"Schwangerschaft\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/eileiterschwangerschaft-1539\\\/\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/eileiterschwangerschaft-1539\\\/\",\"name\":\"Eileiterschwangerschaft - elternforen.com - Ratgeber-Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/eileiterschwangerschaft-1539\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/eileiterschwangerschaft-1539\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/pregnant-6189040_1920.jpg\",\"datePublished\":\"2013-12-10T09:12:03+00:00\",\"dateModified\":\"2022-09-16T09:03:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#\\\/schema\\\/person\\\/ed54c95f56854d06c00044b7c064dfba\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/eileiterschwangerschaft-1539\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/eileiterschwangerschaft-1539\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/eileiterschwangerschaft-1539\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/pregnant-6189040_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/pregnant-6189040_1920.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Schwangerschaft, Bild: Pixabay\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/eileiterschwangerschaft-1539\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eileiterschwangerschaft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#website\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/\",\"name\":\"elternforen.com - Ratgeber-Magazin\",\"description\":\"Der Blog \u00fcber Familie, Schwangerschaft, Babys und Kinder\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#\\\/schema\\\/person\\\/ed54c95f56854d06c00044b7c064dfba\",\"name\":\"Redaktion\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eileiterschwangerschaft - elternforen.com - Ratgeber-Magazin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elternforen.com\/Blog\/eileiterschwangerschaft-1539\/","og_locale":"de_DE","og_type":"article","og_title":"Eileiterschwangerschaft - elternforen.com - Ratgeber-Magazin","og_description":"ANZEIGE - Die Eileiterschwangerschaft ist eine Schwangerschaft au\u00dferhalb der Geb\u00e4rmutter und kommt den offiziellen Zahlen nach, bei 1-2 % der Schwangeren vor. Oft enden viele Eileiterschwangerschaften v\u00f6llig unbemerkt durch eine Fehlgeburt. Zur Fehlgeburt kommt es meistens schon im sehr fr\u00fchen Stadium der Schwangerschaft. Bei einer sogenannten Eileiterschwangerschaft nistet sich das Ei nicht in der Geb\u00e4rmutter [&hellip;]","og_url":"https:\/\/www.elternforen.com\/Blog\/eileiterschwangerschaft-1539\/","og_site_name":"elternforen.com - Ratgeber-Magazin","article_published_time":"2013-12-10T09:12:03+00:00","article_modified_time":"2022-09-16T09:03:08+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2013\/02\/pregnant-6189040_1920.jpg","type":"image\/jpeg"}],"author":"Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Redaktion","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.elternforen.com\/Blog\/eileiterschwangerschaft-1539\/#article","isPartOf":{"@id":"https:\/\/www.elternforen.com\/Blog\/eileiterschwangerschaft-1539\/"},"author":{"name":"Redaktion","@id":"https:\/\/www.elternforen.com\/Blog\/#\/schema\/person\/ed54c95f56854d06c00044b7c064dfba"},"headline":"Eileiterschwangerschaft","datePublished":"2013-12-10T09:12:03+00:00","dateModified":"2022-09-16T09:03:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.elternforen.com\/Blog\/eileiterschwangerschaft-1539\/"},"wordCount":512,"image":{"@id":"https:\/\/www.elternforen.com\/Blog\/eileiterschwangerschaft-1539\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2013\/02\/pregnant-6189040_1920.jpg","keywords":["Eileiterschwangerschaft"],"articleSection":["Schwangerschaft"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.elternforen.com\/Blog\/eileiterschwangerschaft-1539\/","url":"https:\/\/www.elternforen.com\/Blog\/eileiterschwangerschaft-1539\/","name":"Eileiterschwangerschaft - elternforen.com - Ratgeber-Magazin","isPartOf":{"@id":"https:\/\/www.elternforen.com\/Blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elternforen.com\/Blog\/eileiterschwangerschaft-1539\/#primaryimage"},"image":{"@id":"https:\/\/www.elternforen.com\/Blog\/eileiterschwangerschaft-1539\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2013\/02\/pregnant-6189040_1920.jpg","datePublished":"2013-12-10T09:12:03+00:00","dateModified":"2022-09-16T09:03:08+00:00","author":{"@id":"https:\/\/www.elternforen.com\/Blog\/#\/schema\/person\/ed54c95f56854d06c00044b7c064dfba"},"breadcrumb":{"@id":"https:\/\/www.elternforen.com\/Blog\/eileiterschwangerschaft-1539\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elternforen.com\/Blog\/eileiterschwangerschaft-1539\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.elternforen.com\/Blog\/eileiterschwangerschaft-1539\/#primaryimage","url":"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2013\/02\/pregnant-6189040_1920.jpg","contentUrl":"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2013\/02\/pregnant-6189040_1920.jpg","width":1920,"height":1280,"caption":"Schwangerschaft, Bild: Pixabay"},{"@type":"BreadcrumbList","@id":"https:\/\/www.elternforen.com\/Blog\/eileiterschwangerschaft-1539\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elternforen.com\/Blog\/"},{"@type":"ListItem","position":2,"name":"Eileiterschwangerschaft"}]},{"@type":"WebSite","@id":"https:\/\/www.elternforen.com\/Blog\/#website","url":"https:\/\/www.elternforen.com\/Blog\/","name":"elternforen.com - Ratgeber-Magazin","description":"Der Blog \u00fcber Familie, Schwangerschaft, Babys und Kinder","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elternforen.com\/Blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.elternforen.com\/Blog\/#\/schema\/person\/ed54c95f56854d06c00044b7c064dfba","name":"Redaktion","url":"https:\/\/www.elternforen.com\/Blog\/author\/redaktion\/"}]}},"jetpack_featured_media_url":"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2013\/02\/pregnant-6189040_1920.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts\/1539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/comments?post=1539"}],"version-history":[{"count":3,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts\/1539\/revisions"}],"predecessor-version":[{"id":9441,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts\/1539\/revisions\/9441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/media\/9177"}],"wp:attachment":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/media?parent=1539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/categories?post=1539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/tags?post=1539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}