{"id":50,"date":"2008-08-08T20:39:32","date_gmt":"2008-08-08T18:39:32","guid":{"rendered":"http:\/\/www.elternforen.com\/Blog\/vorsorgeuntersuchungen\/"},"modified":"2008-08-08T20:39:32","modified_gmt":"2008-08-08T18:39:32","slug":"vorsorgeuntersuchungen-50","status":"publish","type":"post","link":"https:\/\/www.elternforen.com\/Blog\/vorsorgeuntersuchungen-50\/","title":{"rendered":"Vorsorgeuntersuchungen"},"content":{"rendered":"ANZEIGE - <p>&ldquo;F\u00fcr Mutter und Kind sind <strong>Vorsorgeuntersuchungen<\/strong> sehr wichtig, da m\u00f6gliche Risiken so ausgeschlossen werden k\u00f6nnen.<\/p>\n<p>Lassen sie nie eine aus, auch wenn sie sich sehr wohl f\u00fchlen.<\/p>\n<p>Die Kosten werden von der Krankenkasse \u00fcbernommen.<\/p>\n<p>Vorsorgeuntersuchungen sind von der Feststellung der Schwangerschaft bis zur Geburt wahr zu nehmen.<\/p>\n<p>Die erste richtige Untersuchung beginnt zwischen der achten und zw\u00f6lften Woche.<\/p>\n<p>Bis zu 28 Woche sind einmal im Monat Routineuntersuchungen vorgesehen. Bis zur 36 Woche alle 14 Tage und bis kurz vor der Geburt ist jede Woche mindestens eine Untersuchung ein zu planen.<\/p>\n<p>Auch Berufst\u00e4tige Frauen werde von dem Arbeitgeber f\u00fcr alle <a href=\"http:\/\/www.elternforen.com\/forum24.html\" rel=\"nofollow\" title=\"Vorsorgeuntersuchung\">Vorsorgeuntersuchungen<\/a> freigestellt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANZEIGE &#8211; &ldquo;F\u00fcr Mutter und Kind sind Vorsorgeuntersuchungen sehr wichtig, da m\u00f6gliche Risiken so ausgeschlossen werden k\u00f6nnen. Lassen sie nie eine aus, auch wenn sie sich sehr wohl f\u00fchlen. Die Kosten werden von der Krankenkasse \u00fcbernommen. Vorsorgeuntersuchungen sind von der Feststellung der Schwangerschaft bis zur Geburt wahr zu nehmen. Die erste richtige Untersuchung beginnt zwischen [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[7],"tags":[],"class_list":["post-50","post","type-post","status-publish","format-standard","hentry","category-schwangerschaft"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vorsorgeuntersuchungen - elternforen.com - Ratgeber-Magazin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elternforen.com\/Blog\/vorsorgeuntersuchungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vorsorgeuntersuchungen - elternforen.com - Ratgeber-Magazin\" \/>\n<meta property=\"og:description\" content=\"ANZEIGE - &ldquo;F\u00fcr Mutter und Kind sind Vorsorgeuntersuchungen sehr wichtig, da m\u00f6gliche Risiken so ausgeschlossen werden k\u00f6nnen. Lassen sie nie eine aus, auch wenn sie sich sehr wohl f\u00fchlen. Die Kosten werden von der Krankenkasse \u00fcbernommen. Vorsorgeuntersuchungen sind von der Feststellung der Schwangerschaft bis zur Geburt wahr zu nehmen. Die erste richtige Untersuchung beginnt zwischen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elternforen.com\/Blog\/vorsorgeuntersuchungen\/\" \/>\n<meta property=\"og:site_name\" content=\"elternforen.com - Ratgeber-Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2008-08-08T18:39:32+00:00\" \/>\n<meta name=\"author\" content=\"Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/vorsorgeuntersuchungen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/vorsorgeuntersuchungen\\\/\"},\"author\":{\"name\":\"Redaktion\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#\\\/schema\\\/person\\\/ed54c95f56854d06c00044b7c064dfba\"},\"headline\":\"Vorsorgeuntersuchungen\",\"datePublished\":\"2008-08-08T18:39:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/vorsorgeuntersuchungen\\\/\"},\"wordCount\":107,\"articleSection\":[\"Schwangerschaft\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/vorsorgeuntersuchungen\\\/\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/vorsorgeuntersuchungen\\\/\",\"name\":\"Vorsorgeuntersuchungen - elternforen.com - Ratgeber-Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#website\"},\"datePublished\":\"2008-08-08T18:39:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#\\\/schema\\\/person\\\/ed54c95f56854d06c00044b7c064dfba\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/vorsorgeuntersuchungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/vorsorgeuntersuchungen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/vorsorgeuntersuchungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vorsorgeuntersuchungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#website\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/\",\"name\":\"elternforen.com - Ratgeber-Magazin\",\"description\":\"Der Blog \u00fcber Familie, Schwangerschaft, Babys und Kinder\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#\\\/schema\\\/person\\\/ed54c95f56854d06c00044b7c064dfba\",\"name\":\"Redaktion\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vorsorgeuntersuchungen - elternforen.com - Ratgeber-Magazin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elternforen.com\/Blog\/vorsorgeuntersuchungen\/","og_locale":"de_DE","og_type":"article","og_title":"Vorsorgeuntersuchungen - elternforen.com - Ratgeber-Magazin","og_description":"ANZEIGE - &ldquo;F\u00fcr Mutter und Kind sind Vorsorgeuntersuchungen sehr wichtig, da m\u00f6gliche Risiken so ausgeschlossen werden k\u00f6nnen. Lassen sie nie eine aus, auch wenn sie sich sehr wohl f\u00fchlen. Die Kosten werden von der Krankenkasse \u00fcbernommen. Vorsorgeuntersuchungen sind von der Feststellung der Schwangerschaft bis zur Geburt wahr zu nehmen. Die erste richtige Untersuchung beginnt zwischen [&hellip;]","og_url":"https:\/\/www.elternforen.com\/Blog\/vorsorgeuntersuchungen\/","og_site_name":"elternforen.com - Ratgeber-Magazin","article_published_time":"2008-08-08T18:39:32+00:00","author":"Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Redaktion","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.elternforen.com\/Blog\/vorsorgeuntersuchungen\/#article","isPartOf":{"@id":"https:\/\/www.elternforen.com\/Blog\/vorsorgeuntersuchungen\/"},"author":{"name":"Redaktion","@id":"https:\/\/www.elternforen.com\/Blog\/#\/schema\/person\/ed54c95f56854d06c00044b7c064dfba"},"headline":"Vorsorgeuntersuchungen","datePublished":"2008-08-08T18:39:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.elternforen.com\/Blog\/vorsorgeuntersuchungen\/"},"wordCount":107,"articleSection":["Schwangerschaft"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.elternforen.com\/Blog\/vorsorgeuntersuchungen\/","url":"https:\/\/www.elternforen.com\/Blog\/vorsorgeuntersuchungen\/","name":"Vorsorgeuntersuchungen - elternforen.com - Ratgeber-Magazin","isPartOf":{"@id":"https:\/\/www.elternforen.com\/Blog\/#website"},"datePublished":"2008-08-08T18:39:32+00:00","author":{"@id":"https:\/\/www.elternforen.com\/Blog\/#\/schema\/person\/ed54c95f56854d06c00044b7c064dfba"},"breadcrumb":{"@id":"https:\/\/www.elternforen.com\/Blog\/vorsorgeuntersuchungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elternforen.com\/Blog\/vorsorgeuntersuchungen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.elternforen.com\/Blog\/vorsorgeuntersuchungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elternforen.com\/Blog\/"},{"@type":"ListItem","position":2,"name":"Vorsorgeuntersuchungen"}]},{"@type":"WebSite","@id":"https:\/\/www.elternforen.com\/Blog\/#website","url":"https:\/\/www.elternforen.com\/Blog\/","name":"elternforen.com - Ratgeber-Magazin","description":"Der Blog \u00fcber Familie, Schwangerschaft, Babys und Kinder","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elternforen.com\/Blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.elternforen.com\/Blog\/#\/schema\/person\/ed54c95f56854d06c00044b7c064dfba","name":"Redaktion","url":"https:\/\/www.elternforen.com\/Blog\/author\/redaktion\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/comments?post=50"}],"version-history":[{"count":0,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts\/50\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/media?parent=50"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/categories?post=50"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/tags?post=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}