{"id":5205,"date":"2020-06-06T12:02:07","date_gmt":"2020-06-06T10:02:07","guid":{"rendered":"http:\/\/www.elternforen.com\/Blog\/?p=5205"},"modified":"2020-06-06T12:02:07","modified_gmt":"2020-06-06T10:02:07","slug":"wie-kann-eine-ehekrise-bewaeltigt-werden-5205","status":"publish","type":"post","link":"https:\/\/www.elternforen.com\/Blog\/wie-kann-eine-ehekrise-bewaeltigt-werden-5205\/","title":{"rendered":"Wie kann eine Ehekrise bew\u00e4ltigt werden?"},"content":{"rendered":"ANZEIGE - <p>Die aktuelle Corona-Krise stellt viele Ehepaare vor eine gro\u00dfe Herausforderung. Durch die Kontaktbeschr\u00e4nkungen und das Arbeiten im Home-Office verbringen viele Paare vermehrt Zeit zu Hause. Das Zusammensein auf engem Raum kann dabei zu Spannungen f\u00fchren und sich im schlimmsten Fall zu einer Ehekrise entwickeln. Mit einigen Tipps k\u00f6nnen Sie das Risiko reduzieren, dass Ihre Ehe an dieser extremen Herausforderung zerbricht.<\/p>\n<h2>Der erste Schritt: sich selbst eingestehen, dass es Probleme gibt<\/h2>\n<p>Der erste Schritt, um eine Ehekrise zu bew\u00e4ltigen ist, sich diese einzugestehen. Sie sollten sich bewusst machen, dass es so wie es ist nicht mehr weitergeht. Wollen Sie Ihre <a href=\"https:\/\/www.transaktionsanalyse-online.de\/ehekrise\/\">Ehekrise bew\u00e4ltigen<\/a>, m\u00fcssen Ver\u00e4nderungen geschehen. Um die negativen Gef\u00fchle \u00fcberwinden und Ihre Ehe retten zu k\u00f6nnen, m\u00fcssen Sie aktiv auf Ihren Partner zugehen und die vorhandenen Probleme offen ansprechen. Analysieren Sie zun\u00e4chst gemeinsam die Streitpunkte und Differenzen. Dabei sollten Sie jedoch nicht jede Kleinigkeit ansprechen, die Sie st\u00f6rt, sondern sich auf gravierende Probleme beschr\u00e4nken. Anschlie\u00dfend setzen Sie sich gemeinsam mit Ihrem Ehepartner Ziele, die Sie erreichen m\u00f6chten. Es ist wichtig, dass Sie sich Zeit als Paar nehmen. In einigen F\u00e4llen hilft eine zeitliche oder r\u00e4umliche Trennung, um wieder zueinander zu finden. Da die r\u00e4umliche Trennung w\u00e4hrend der Corona-Krise nicht leicht umsetzbar ist, sollten Sie dennoch darauf achten, dass sowohl Sie als auch Ihr Partner \u00fcber einen R\u00fcckzugsort verf\u00fcgen. Ein R\u00fcckzugsort ist wichtig, um Zeit f\u00fcr sich selbst zu haben und neue Kraft zu sch\u00f6pfen.<\/p>\n<h2>Der zweite Schritt: bei anderen um Rat fragen<\/h2>\n<p>Um Ihre Ehekrise zu \u00fcberwinden, ist es zudem \u00e4u\u00dferst empfehlenswert sich mit Personen in Verbindung zu setzen, die sich in der gleichen Situation befinden oder bereits eine Ehekrise \u00fcberwunden haben. Sprechen Sie hierzu offen mit Freunden, Bekannten oder Ihrer Familie. Es gibt auch <a href=\"http:\/\/www.elternforen.com\/threads\/ehe-krise-oder-das-ende.35754\/\">Hilfe zur Ehekrise<\/a> in Foren. Hier treffen Sie auf Menschen, die eventuell bereits einen L\u00f6sungsweg gefunden haben und k\u00f6nnen sich mit diesen austauschen. Auch ein Coaching f\u00fcr Paare oder eine Eheberatung k\u00f6nnen in Frage kommen, um Ihre Probleme zu bew\u00e4ltigen. In jedem Fall sollten Sie sich Hilfe von au\u00dfen suchen. Sie werden schnell merken, dass Sie mit Ihren Fragen und Problemen nicht allein dastehen.<\/p>\n<h2>Der dritte Schritt: wieder zusammenfinden<\/h2>\n<p>Der letzte Schritt, um die Krise zu \u00fcberwinden ist, dass Sie wieder <a href=\"https:\/\/www.stern.de\/fotografie\/akt\/wie-paare-wieder-zusammen-finden-koennen-leere-nach-dem-sturm-3506358.html\">mit Ihrem Partner zusammenfinden<\/a>. Besonders wichtig ist hierbei, dass Sie sich gen\u00fcgend Zeit als Paar nehmen. Denn gerade dann, wenn auch Kinder im Haushalt leben, kommt diese Zeit oftmals zu kurz. Achten Sie darauf, gemeinsame Zeit zu verbringen. Dies muss nicht immer ein Restaurant- oder Kinobesuch sein. Bereits ein gemeinsamer Spaziergang oder das Filmeschauen, schwei\u00dfen zusammen.<\/p>\n<h2>Fazit: Eine Ehekrise muss nicht das Ende bedeuten<\/h2>\n<p>Wenn Sie sich in einer Ehekrise befinden, hei\u00dft das nicht, dass Ihre Ehe bereits am Ende ist. Zun\u00e4chst m\u00fcssen Sie sich selbst dar\u00fcber bewusstwerden, dass Probleme vorhanden sind. Besprechen Sie diese mit Ihrem Ehepartner und finden Sie gemeinsam L\u00f6sungen. Der Austausch in Foren kann dabei helfen, die Krise zu \u00fcberwinden. Hier treffen Sie auf Menschen, die mit den gleichen Problemen zu k\u00e4mpfen haben. Ebenso kommt ein Partnercoaching oder eine Eheberatung in Frage.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANZEIGE &#8211; Die aktuelle Corona-Krise stellt viele Ehepaare vor eine gro\u00dfe Herausforderung. Durch die Kontaktbeschr\u00e4nkungen und das Arbeiten im Home-Office verbringen viele Paare vermehrt Zeit zu Hause. Das Zusammensein auf engem Raum kann dabei zu Spannungen f\u00fchren und sich im schlimmsten Fall zu einer Ehekrise entwickeln. Mit einigen Tipps k\u00f6nnen Sie das Risiko reduzieren, dass [&hellip;]<\/p>\n","protected":false},"author":62,"featured_media":5207,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-5205","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-familie-und-beruf"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wie kann eine Ehekrise bew\u00e4ltigt werden? - elternforen.com - Ratgeber-Magazin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elternforen.com\/Blog\/wie-kann-eine-ehekrise-bewaeltigt-werden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie kann eine Ehekrise bew\u00e4ltigt werden? - elternforen.com - Ratgeber-Magazin\" \/>\n<meta property=\"og:description\" content=\"ANZEIGE - Die aktuelle Corona-Krise stellt viele Ehepaare vor eine gro\u00dfe Herausforderung. Durch die Kontaktbeschr\u00e4nkungen und das Arbeiten im Home-Office verbringen viele Paare vermehrt Zeit zu Hause. Das Zusammensein auf engem Raum kann dabei zu Spannungen f\u00fchren und sich im schlimmsten Fall zu einer Ehekrise entwickeln. Mit einigen Tipps k\u00f6nnen Sie das Risiko reduzieren, dass [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elternforen.com\/Blog\/wie-kann-eine-ehekrise-bewaeltigt-werden\/\" \/>\n<meta property=\"og:site_name\" content=\"elternforen.com - Ratgeber-Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-06T10:02:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2020\/06\/breakup-908714_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"847\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wie-kann-eine-ehekrise-bewaeltigt-werden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wie-kann-eine-ehekrise-bewaeltigt-werden\\\/\"},\"author\":{\"name\":\"redaktion\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#\\\/schema\\\/person\\\/979a88c5d2ec2beabc8f0e00243558c3\"},\"headline\":\"Wie kann eine Ehekrise bew\u00e4ltigt werden?\",\"datePublished\":\"2020-06-06T10:02:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wie-kann-eine-ehekrise-bewaeltigt-werden\\\/\"},\"wordCount\":548,\"image\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wie-kann-eine-ehekrise-bewaeltigt-werden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/breakup-908714_1280.jpg\",\"articleSection\":[\"Familie und Beruf\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wie-kann-eine-ehekrise-bewaeltigt-werden\\\/\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wie-kann-eine-ehekrise-bewaeltigt-werden\\\/\",\"name\":\"Wie kann eine Ehekrise bew\u00e4ltigt werden? - elternforen.com - Ratgeber-Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wie-kann-eine-ehekrise-bewaeltigt-werden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wie-kann-eine-ehekrise-bewaeltigt-werden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/breakup-908714_1280.jpg\",\"datePublished\":\"2020-06-06T10:02:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#\\\/schema\\\/person\\\/979a88c5d2ec2beabc8f0e00243558c3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wie-kann-eine-ehekrise-bewaeltigt-werden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wie-kann-eine-ehekrise-bewaeltigt-werden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wie-kann-eine-ehekrise-bewaeltigt-werden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/breakup-908714_1280.jpg\",\"contentUrl\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/breakup-908714_1280.jpg\",\"width\":1280,\"height\":847},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wie-kann-eine-ehekrise-bewaeltigt-werden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wie kann eine Ehekrise bew\u00c3\u00a4ltigt werden?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#website\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/\",\"name\":\"elternforen.com - Ratgeber-Magazin\",\"description\":\"Der Blog \u00fcber Familie, Schwangerschaft, Babys und Kinder\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#\\\/schema\\\/person\\\/979a88c5d2ec2beabc8f0e00243558c3\",\"name\":\"redaktion\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/author\\\/stefan\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie kann eine Ehekrise bew\u00e4ltigt werden? - elternforen.com - Ratgeber-Magazin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elternforen.com\/Blog\/wie-kann-eine-ehekrise-bewaeltigt-werden\/","og_locale":"de_DE","og_type":"article","og_title":"Wie kann eine Ehekrise bew\u00e4ltigt werden? - elternforen.com - Ratgeber-Magazin","og_description":"ANZEIGE - Die aktuelle Corona-Krise stellt viele Ehepaare vor eine gro\u00dfe Herausforderung. Durch die Kontaktbeschr\u00e4nkungen und das Arbeiten im Home-Office verbringen viele Paare vermehrt Zeit zu Hause. Das Zusammensein auf engem Raum kann dabei zu Spannungen f\u00fchren und sich im schlimmsten Fall zu einer Ehekrise entwickeln. Mit einigen Tipps k\u00f6nnen Sie das Risiko reduzieren, dass [&hellip;]","og_url":"https:\/\/www.elternforen.com\/Blog\/wie-kann-eine-ehekrise-bewaeltigt-werden\/","og_site_name":"elternforen.com - Ratgeber-Magazin","article_published_time":"2020-06-06T10:02:07+00:00","og_image":[{"width":1280,"height":847,"url":"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2020\/06\/breakup-908714_1280.jpg","type":"image\/jpeg"}],"author":"redaktion","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"redaktion","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.elternforen.com\/Blog\/wie-kann-eine-ehekrise-bewaeltigt-werden\/#article","isPartOf":{"@id":"https:\/\/www.elternforen.com\/Blog\/wie-kann-eine-ehekrise-bewaeltigt-werden\/"},"author":{"name":"redaktion","@id":"https:\/\/www.elternforen.com\/Blog\/#\/schema\/person\/979a88c5d2ec2beabc8f0e00243558c3"},"headline":"Wie kann eine Ehekrise bew\u00e4ltigt werden?","datePublished":"2020-06-06T10:02:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.elternforen.com\/Blog\/wie-kann-eine-ehekrise-bewaeltigt-werden\/"},"wordCount":548,"image":{"@id":"https:\/\/www.elternforen.com\/Blog\/wie-kann-eine-ehekrise-bewaeltigt-werden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2020\/06\/breakup-908714_1280.jpg","articleSection":["Familie und Beruf"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.elternforen.com\/Blog\/wie-kann-eine-ehekrise-bewaeltigt-werden\/","url":"https:\/\/www.elternforen.com\/Blog\/wie-kann-eine-ehekrise-bewaeltigt-werden\/","name":"Wie kann eine Ehekrise bew\u00e4ltigt werden? - elternforen.com - Ratgeber-Magazin","isPartOf":{"@id":"https:\/\/www.elternforen.com\/Blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elternforen.com\/Blog\/wie-kann-eine-ehekrise-bewaeltigt-werden\/#primaryimage"},"image":{"@id":"https:\/\/www.elternforen.com\/Blog\/wie-kann-eine-ehekrise-bewaeltigt-werden\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2020\/06\/breakup-908714_1280.jpg","datePublished":"2020-06-06T10:02:07+00:00","author":{"@id":"https:\/\/www.elternforen.com\/Blog\/#\/schema\/person\/979a88c5d2ec2beabc8f0e00243558c3"},"breadcrumb":{"@id":"https:\/\/www.elternforen.com\/Blog\/wie-kann-eine-ehekrise-bewaeltigt-werden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elternforen.com\/Blog\/wie-kann-eine-ehekrise-bewaeltigt-werden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.elternforen.com\/Blog\/wie-kann-eine-ehekrise-bewaeltigt-werden\/#primaryimage","url":"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2020\/06\/breakup-908714_1280.jpg","contentUrl":"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2020\/06\/breakup-908714_1280.jpg","width":1280,"height":847},{"@type":"BreadcrumbList","@id":"https:\/\/www.elternforen.com\/Blog\/wie-kann-eine-ehekrise-bewaeltigt-werden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elternforen.com\/Blog\/"},{"@type":"ListItem","position":2,"name":"Wie kann eine Ehekrise bew\u00c3\u00a4ltigt werden?"}]},{"@type":"WebSite","@id":"https:\/\/www.elternforen.com\/Blog\/#website","url":"https:\/\/www.elternforen.com\/Blog\/","name":"elternforen.com - Ratgeber-Magazin","description":"Der Blog \u00fcber Familie, Schwangerschaft, Babys und Kinder","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elternforen.com\/Blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.elternforen.com\/Blog\/#\/schema\/person\/979a88c5d2ec2beabc8f0e00243558c3","name":"redaktion","url":"https:\/\/www.elternforen.com\/Blog\/author\/stefan\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2020\/06\/breakup-908714_1280.jpg","_links":{"self":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts\/5205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/comments?post=5205"}],"version-history":[{"count":1,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts\/5205\/revisions"}],"predecessor-version":[{"id":5208,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts\/5205\/revisions\/5208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/media\/5207"}],"wp:attachment":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/media?parent=5205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/categories?post=5205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/tags?post=5205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}