{"id":94,"date":"2009-03-24T23:07:06","date_gmt":"2009-03-24T21:07:06","guid":{"rendered":"http:\/\/www.elternforen.com\/Blog\/?p=94"},"modified":"2009-03-24T23:14:11","modified_gmt":"2009-03-24T21:14:11","slug":"fit-ins-fruhjahr-94","status":"publish","type":"post","link":"https:\/\/www.elternforen.com\/Blog\/fit-ins-fruhjahr-94\/","title":{"rendered":"Fit ins Fr\u00fchjahr"},"content":{"rendered":"ANZEIGE - <p>Die ersten Fr\u00fchlingsblumen strecken ihre K\u00f6pfchen gen Himmel, ein laues M\u00e4rzl\u00fcftchen k\u00fcndigt den nahenden Fr\u00fchling an. Nun l\u00e4uft die Natur zu H\u00f6chstleistungen auf. Im Gegensatz dazu machen allerdings viele Menschen schlapp. Die Fr\u00fchjahrsm\u00fcdigkeit breitet sich aus. Au\u00dferdem scheint diese irgendwie ansteckend zu sein, denn warum sonst f\u00fchlten sich alle Freunde, mit denen man \u00fcber die verschiedenen Symptome spricht, genauso schlapp?<\/p>\n<p>Nat\u00fcrlich ist die Fr\u00fchjahrsm\u00fcdigkeit nicht wirklich ansteckend. Allerdings kommt sie p\u00fcnktlich in jedem Jahr zum Fr\u00fchlingsbeginn. Ihre Symptome reichen von M\u00fcdigkeit und einem erh\u00f6hten Schlafbed\u00fcrfnis bis hin zu gereizter Stimmung und schw\u00e4chelndem Kreislauf.<\/p>\n<p>Eine wichtige Rolle bei dieser &bdquo;Krankheit&ldquo; spielt die Wetterumstellung. Nach dem langen Winter ziehen nun die ersten w\u00e4rmeren Tage ins Land. Die Blutgef\u00e4\u00dfe weiten sich, der Blutdruck sinkt und als Folge f\u00fchlen sich viele Menschen m\u00fcde und schlapp. Dar\u00fcber hinaus muss sich der gesamte Organismus nun erst einmal von der dunklen Jahreszeit auf eine helle umstellen.<\/p>\n<p>Nat\u00fcrlich muss man die Fr\u00fchjahrsm\u00fcdigkeit nicht einfach als gegeben hinnehmen. Etwas wehren dagegen kann man sich schon. So sollte man sich, wenn m\u00f6glich, seinen Tagesablauf so einteilen, dass man m\u00f6glichst fr\u00fch aufsteht und auch fr\u00fch wieder schlafen geht. Unter dem Einfluss des Lichtes am Tage wird das Hormon Melatonin abgebaut und Serotonin gebildet.<\/p>\n<p>Auch sportliche Bet\u00e4tigung wirkt gegen die Fr\u00fchjahrsm\u00fcdigkeit. Spazierg\u00e4nge an der frischen Luft, Radtouren mit Freunden, Treppensteigen statt Lift, all das sorgt f\u00fcr Frische und Munterkeit. Daneben hat der Sport noch einen weiteren positiven Nebeneffekt. Der \u00fcber den Winter angefutterte &bdquo;Winterspeck&ldquo; schmilzt so allm\u00e4hlich dahin.<\/p>\n<p>Ein weiterer Tipp betrifft die Ern\u00e4hrung. Frische, vitaminreiche Kost kurbelt den Stoffwechsel an und macht weder tr\u00e4ge noch m\u00fcde. Mehrere kleine, statt drei gro\u00dfe Mahlzeiten sind empfehlenswert.<\/p>\n<p>Mit jedem Fr\u00fchlingstag wird nun die Laune steigen und von Fr\u00fchjahrsm\u00fcdigkeit bleibt keine Spur mehr.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANZEIGE &#8211; Die ersten Fr\u00fchlingsblumen strecken ihre K\u00f6pfchen gen Himmel, ein laues M\u00e4rzl\u00fcftchen k\u00fcndigt den nahenden Fr\u00fchling an. Nun l\u00e4uft die Natur zu H\u00f6chstleistungen auf. Im Gegensatz dazu machen allerdings viele Menschen schlapp. Die Fr\u00fchjahrsm\u00fcdigkeit breitet sich aus. Au\u00dferdem scheint diese irgendwie ansteckend zu sein, denn warum sonst f\u00fchlten sich alle Freunde, mit denen man [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-94","post","type-post","status-publish","format-standard","hentry","category-besondere-themen"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fit ins Fr\u00fchjahr - elternforen.com - Ratgeber-Magazin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elternforen.com\/Blog\/fit-ins-fruhjahr\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fit ins Fr\u00fchjahr - elternforen.com - Ratgeber-Magazin\" \/>\n<meta property=\"og:description\" content=\"ANZEIGE - Die ersten Fr\u00fchlingsblumen strecken ihre K\u00f6pfchen gen Himmel, ein laues M\u00e4rzl\u00fcftchen k\u00fcndigt den nahenden Fr\u00fchling an. Nun l\u00e4uft die Natur zu H\u00f6chstleistungen auf. Im Gegensatz dazu machen allerdings viele Menschen schlapp. Die Fr\u00fchjahrsm\u00fcdigkeit breitet sich aus. Au\u00dferdem scheint diese irgendwie ansteckend zu sein, denn warum sonst f\u00fchlten sich alle Freunde, mit denen man [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elternforen.com\/Blog\/fit-ins-fruhjahr\/\" \/>\n<meta property=\"og:site_name\" content=\"elternforen.com - Ratgeber-Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2009-03-24T21:07:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2009-03-24T21:14:11+00:00\" \/>\n<meta name=\"author\" content=\"Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/fit-ins-fruhjahr\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/fit-ins-fruhjahr\\\/\"},\"author\":{\"name\":\"Redaktion\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#\\\/schema\\\/person\\\/ed54c95f56854d06c00044b7c064dfba\"},\"headline\":\"Fit ins Fr\u00fchjahr\",\"datePublished\":\"2009-03-24T21:07:06+00:00\",\"dateModified\":\"2009-03-24T21:14:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/fit-ins-fruhjahr\\\/\"},\"wordCount\":342,\"articleSection\":[\"Besondere Themen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/fit-ins-fruhjahr\\\/\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/fit-ins-fruhjahr\\\/\",\"name\":\"Fit ins Fr\u00fchjahr - elternforen.com - Ratgeber-Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#website\"},\"datePublished\":\"2009-03-24T21:07:06+00:00\",\"dateModified\":\"2009-03-24T21:14:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#\\\/schema\\\/person\\\/ed54c95f56854d06c00044b7c064dfba\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/fit-ins-fruhjahr\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/fit-ins-fruhjahr\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/fit-ins-fruhjahr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fit ins Fr\u00c3\u00bchjahr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#website\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/\",\"name\":\"elternforen.com - Ratgeber-Magazin\",\"description\":\"Der Blog \u00fcber Familie, Schwangerschaft, Babys und Kinder\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#\\\/schema\\\/person\\\/ed54c95f56854d06c00044b7c064dfba\",\"name\":\"Redaktion\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fit ins Fr\u00fchjahr - elternforen.com - Ratgeber-Magazin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elternforen.com\/Blog\/fit-ins-fruhjahr\/","og_locale":"de_DE","og_type":"article","og_title":"Fit ins Fr\u00fchjahr - elternforen.com - Ratgeber-Magazin","og_description":"ANZEIGE - Die ersten Fr\u00fchlingsblumen strecken ihre K\u00f6pfchen gen Himmel, ein laues M\u00e4rzl\u00fcftchen k\u00fcndigt den nahenden Fr\u00fchling an. Nun l\u00e4uft die Natur zu H\u00f6chstleistungen auf. Im Gegensatz dazu machen allerdings viele Menschen schlapp. Die Fr\u00fchjahrsm\u00fcdigkeit breitet sich aus. Au\u00dferdem scheint diese irgendwie ansteckend zu sein, denn warum sonst f\u00fchlten sich alle Freunde, mit denen man [&hellip;]","og_url":"https:\/\/www.elternforen.com\/Blog\/fit-ins-fruhjahr\/","og_site_name":"elternforen.com - Ratgeber-Magazin","article_published_time":"2009-03-24T21:07:06+00:00","article_modified_time":"2009-03-24T21:14:11+00:00","author":"Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Redaktion","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.elternforen.com\/Blog\/fit-ins-fruhjahr\/#article","isPartOf":{"@id":"https:\/\/www.elternforen.com\/Blog\/fit-ins-fruhjahr\/"},"author":{"name":"Redaktion","@id":"https:\/\/www.elternforen.com\/Blog\/#\/schema\/person\/ed54c95f56854d06c00044b7c064dfba"},"headline":"Fit ins Fr\u00fchjahr","datePublished":"2009-03-24T21:07:06+00:00","dateModified":"2009-03-24T21:14:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.elternforen.com\/Blog\/fit-ins-fruhjahr\/"},"wordCount":342,"articleSection":["Besondere Themen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.elternforen.com\/Blog\/fit-ins-fruhjahr\/","url":"https:\/\/www.elternforen.com\/Blog\/fit-ins-fruhjahr\/","name":"Fit ins Fr\u00fchjahr - elternforen.com - Ratgeber-Magazin","isPartOf":{"@id":"https:\/\/www.elternforen.com\/Blog\/#website"},"datePublished":"2009-03-24T21:07:06+00:00","dateModified":"2009-03-24T21:14:11+00:00","author":{"@id":"https:\/\/www.elternforen.com\/Blog\/#\/schema\/person\/ed54c95f56854d06c00044b7c064dfba"},"breadcrumb":{"@id":"https:\/\/www.elternforen.com\/Blog\/fit-ins-fruhjahr\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elternforen.com\/Blog\/fit-ins-fruhjahr\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.elternforen.com\/Blog\/fit-ins-fruhjahr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elternforen.com\/Blog\/"},{"@type":"ListItem","position":2,"name":"Fit ins Fr\u00c3\u00bchjahr"}]},{"@type":"WebSite","@id":"https:\/\/www.elternforen.com\/Blog\/#website","url":"https:\/\/www.elternforen.com\/Blog\/","name":"elternforen.com - Ratgeber-Magazin","description":"Der Blog \u00fcber Familie, Schwangerschaft, Babys und Kinder","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elternforen.com\/Blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.elternforen.com\/Blog\/#\/schema\/person\/ed54c95f56854d06c00044b7c064dfba","name":"Redaktion","url":"https:\/\/www.elternforen.com\/Blog\/author\/redaktion\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts\/94","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/comments?post=94"}],"version-history":[{"count":2,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts\/94\/revisions"}],"predecessor-version":[{"id":106,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts\/94\/revisions\/106"}],"wp:attachment":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/media?parent=94"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/categories?post=94"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/tags?post=94"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}