{"id":989,"date":"2013-05-16T21:11:46","date_gmt":"2013-05-16T19:11:46","guid":{"rendered":"http:\/\/www.elternforen.com\/Blog\/?p=989"},"modified":"2022-09-16T08:55:59","modified_gmt":"2022-09-16T06:55:59","slug":"unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989","status":"publish","type":"post","link":"https:\/\/www.elternforen.com\/Blog\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\/","title":{"rendered":"Unbedenkliche Hausmittel bei einer Blasenentz\u00fcndung f\u00fcr Schwangere"},"content":{"rendered":"ANZEIGE - <p>Frauen werden aufgrund ihrer besonderen Anatomie \u00f6fter von Blasenentz\u00fcndungen geplagt als M\u00e4nner. Da die Harnr\u00f6hre mit 3 bis 5 cm sehr kurz ist, k\u00f6nnen Keime viel leichter die Blase erreichen, bevor sie mit dem Urin wieder ausgesp\u00fclt werden. H\u00e4ufig werden Blasenentz\u00fcndungen mit Antibiotika behandelt. Auch bei schwangeren Patientinnen. Doch das ist nicht immer notwendig. Dar\u00fcber hinaus macht eine antibiotische Behandlung nur nach einem Antibiogramm des Urins Sinn. Dabei werden in einer aktuellen Urinprobe die verursachenden Keime festgestellt und auf Ihre Empfindlichkeit oder eventuelle Resistenz gegen\u00fcber \u00fcblichen Antibiotika getestet. Viele Antworten \u00fcber Symptome und ihre Ursachen k\u00f6nnen unter <a href=\"http:\/\/www.netdoktor.de\/symptome\/blut-im-urin\/\" rel=\"nofollow\"><span style=\"text-decoration: underline;\">http:\/\/www.netdoktor.de\/symptome\/blut-im-urin\/<\/span><\/a> nachgelesen werden.<\/p>\n<p>Doch es gibt auch sanfte Methoden, eine <a href=\"http:\/\/www.elternforen.com\/schwangerschaftskomplikationen-f26\/blasenentzuendung-t8994\/1\/\" rel=\"nofollow\">Blasenentz\u00fcndung <\/a>erfolgreich zu behandeln. Vor allem in der Schwangerschaft m\u00f6chten die werdenden M\u00fctter auf Chemie verzichten. H\u00e4ufig reicht das Durchsp\u00fclen der Harnwege durch reichliches Trinken aus. Gut geeignet \u201csind Teesorten wie Birkenbl\u00e4tter oder Brennnessel. 3 bis 4 Tassen \u00fcber den Tag verteilt in kleinen Schlucken trinken. Dazwischen wird am besten Mineralwasser getrunken. Bauch und R\u00fccken warmhalten. Auf harntreibende Tees aus Goldrute oder Ackerschachtelhalm sollte in der Schwangerschaft verzichtet werden, da sie unter Umst\u00e4nden recht heftige Reaktionen der Nieren hervorrufen. Ebenfalls ungeeignet sind Holunderbl\u00fcten oder Petersilienwurzeln, da sie stark Wehen treibend sind.<\/p>\n<p>Die Trinkmenge soll 2-3 Liter nicht \u00fcberschreiten und gut \u00fcber den gesamten Tag verteilt werden. Sonst kann der Mineralstoffhaushalt betr\u00e4chtlich in seinem Gleichgewicht gest\u00f6rt werden. Denn \u00fcber die Niere werden auch einige Mineralstoffe, wie zum Beispiel Kalium ausgeschieden.<\/p>\n<p>Eine antibiotische Wirkung haben Zubereitungen aus B\u00e4rentraubenbl\u00e4ttern, Preiselbeeren oder Cranberrys. Doch auch hierbei muss die Dosierung und die Einnahmedauer beachtet werden.<\/p>\n<p>Eine Blasenentz\u00fcndung kann ebenfalls gut hom\u00f6opathisch behandelt werden. Gegen starken Harndrang und dem h\u00e4ufigen Lassen kleiner Mengen Urin, verbunden mit Blutbeimischungen und starken Schmerzen eignet sich Cantharis D6 sehr gut. Hier reicht schon eine einmalige Gabe aus, um die Beschwerden zu lindern.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANZEIGE &#8211; Frauen werden aufgrund ihrer besonderen Anatomie \u00f6fter von Blasenentz\u00fcndungen geplagt als M\u00e4nner. Da die Harnr\u00f6hre mit 3 bis 5 cm sehr kurz ist, k\u00f6nnen Keime viel leichter die Blase erreichen, bevor sie mit dem Urin wieder ausgesp\u00fclt werden. H\u00e4ufig werden Blasenentz\u00fcndungen mit Antibiotika behandelt. Auch bei schwangeren Patientinnen. Doch das ist nicht immer [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":9180,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[12],"tags":[289],"class_list":["post-989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-besondere-themen","tag-blasenentzundung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unbedenkliche Hausmittel bei einer Blasenentz\u00fcndung f\u00fcr Schwangere - elternforen.com - Ratgeber-Magazin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.elternforen.com\/Blog\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unbedenkliche Hausmittel bei einer Blasenentz\u00fcndung f\u00fcr Schwangere - elternforen.com - Ratgeber-Magazin\" \/>\n<meta property=\"og:description\" content=\"ANZEIGE - Frauen werden aufgrund ihrer besonderen Anatomie \u00f6fter von Blasenentz\u00fcndungen geplagt als M\u00e4nner. Da die Harnr\u00f6hre mit 3 bis 5 cm sehr kurz ist, k\u00f6nnen Keime viel leichter die Blase erreichen, bevor sie mit dem Urin wieder ausgesp\u00fclt werden. H\u00e4ufig werden Blasenentz\u00fcndungen mit Antibiotika behandelt. Auch bei schwangeren Patientinnen. Doch das ist nicht immer [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.elternforen.com\/Blog\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\/\" \/>\n<meta property=\"og:site_name\" content=\"elternforen.com - Ratgeber-Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-16T19:11:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-16T06:55:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2013\/02\/woman-3186730_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1283\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\\\/\"},\"author\":{\"name\":\"Redaktion\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#\\\/schema\\\/person\\\/ed54c95f56854d06c00044b7c064dfba\"},\"headline\":\"Unbedenkliche Hausmittel bei einer Blasenentz\u00fcndung f\u00fcr Schwangere\",\"datePublished\":\"2013-05-16T19:11:46+00:00\",\"dateModified\":\"2022-09-16T06:55:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\\\/\"},\"wordCount\":335,\"image\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/woman-3186730_1920.jpg\",\"keywords\":[\"Blasenentz\u00fcndung\"],\"articleSection\":[\"Besondere Themen\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\\\/\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\\\/\",\"name\":\"Unbedenkliche Hausmittel bei einer Blasenentz\u00fcndung f\u00fcr Schwangere - elternforen.com - Ratgeber-Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/woman-3186730_1920.jpg\",\"datePublished\":\"2013-05-16T19:11:46+00:00\",\"dateModified\":\"2022-09-16T06:55:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#\\\/schema\\\/person\\\/ed54c95f56854d06c00044b7c064dfba\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/woman-3186730_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/woman-3186730_1920.jpg\",\"width\":1920,\"height\":1283,\"caption\":\"PMS-Beschwerden, Bild: Pixabay\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unbedenkliche Hausmittel bei einer Blasenentz\u00fcndung f\u00fcr Schwangere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#website\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/\",\"name\":\"elternforen.com - Ratgeber-Magazin\",\"description\":\"Der Blog \u00fcber Familie, Schwangerschaft, Babys und Kinder\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/#\\\/schema\\\/person\\\/ed54c95f56854d06c00044b7c064dfba\",\"name\":\"Redaktion\",\"url\":\"https:\\\/\\\/www.elternforen.com\\\/Blog\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unbedenkliche Hausmittel bei einer Blasenentz\u00fcndung f\u00fcr Schwangere - elternforen.com - Ratgeber-Magazin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.elternforen.com\/Blog\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\/","og_locale":"de_DE","og_type":"article","og_title":"Unbedenkliche Hausmittel bei einer Blasenentz\u00fcndung f\u00fcr Schwangere - elternforen.com - Ratgeber-Magazin","og_description":"ANZEIGE - Frauen werden aufgrund ihrer besonderen Anatomie \u00f6fter von Blasenentz\u00fcndungen geplagt als M\u00e4nner. Da die Harnr\u00f6hre mit 3 bis 5 cm sehr kurz ist, k\u00f6nnen Keime viel leichter die Blase erreichen, bevor sie mit dem Urin wieder ausgesp\u00fclt werden. H\u00e4ufig werden Blasenentz\u00fcndungen mit Antibiotika behandelt. Auch bei schwangeren Patientinnen. Doch das ist nicht immer [&hellip;]","og_url":"https:\/\/www.elternforen.com\/Blog\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\/","og_site_name":"elternforen.com - Ratgeber-Magazin","article_published_time":"2013-05-16T19:11:46+00:00","article_modified_time":"2022-09-16T06:55:59+00:00","og_image":[{"width":1920,"height":1283,"url":"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2013\/02\/woman-3186730_1920.jpg","type":"image\/jpeg"}],"author":"Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Redaktion","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.elternforen.com\/Blog\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\/#article","isPartOf":{"@id":"https:\/\/www.elternforen.com\/Blog\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\/"},"author":{"name":"Redaktion","@id":"https:\/\/www.elternforen.com\/Blog\/#\/schema\/person\/ed54c95f56854d06c00044b7c064dfba"},"headline":"Unbedenkliche Hausmittel bei einer Blasenentz\u00fcndung f\u00fcr Schwangere","datePublished":"2013-05-16T19:11:46+00:00","dateModified":"2022-09-16T06:55:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.elternforen.com\/Blog\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\/"},"wordCount":335,"image":{"@id":"https:\/\/www.elternforen.com\/Blog\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2013\/02\/woman-3186730_1920.jpg","keywords":["Blasenentz\u00fcndung"],"articleSection":["Besondere Themen"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.elternforen.com\/Blog\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\/","url":"https:\/\/www.elternforen.com\/Blog\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\/","name":"Unbedenkliche Hausmittel bei einer Blasenentz\u00fcndung f\u00fcr Schwangere - elternforen.com - Ratgeber-Magazin","isPartOf":{"@id":"https:\/\/www.elternforen.com\/Blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.elternforen.com\/Blog\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\/#primaryimage"},"image":{"@id":"https:\/\/www.elternforen.com\/Blog\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\/#primaryimage"},"thumbnailUrl":"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2013\/02\/woman-3186730_1920.jpg","datePublished":"2013-05-16T19:11:46+00:00","dateModified":"2022-09-16T06:55:59+00:00","author":{"@id":"https:\/\/www.elternforen.com\/Blog\/#\/schema\/person\/ed54c95f56854d06c00044b7c064dfba"},"breadcrumb":{"@id":"https:\/\/www.elternforen.com\/Blog\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.elternforen.com\/Blog\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.elternforen.com\/Blog\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\/#primaryimage","url":"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2013\/02\/woman-3186730_1920.jpg","contentUrl":"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2013\/02\/woman-3186730_1920.jpg","width":1920,"height":1283,"caption":"PMS-Beschwerden, Bild: Pixabay"},{"@type":"BreadcrumbList","@id":"https:\/\/www.elternforen.com\/Blog\/unbedenkliche-hausmittel-bei-einer-blasenentzundung-fur-schwangere-989\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.elternforen.com\/Blog\/"},{"@type":"ListItem","position":2,"name":"Unbedenkliche Hausmittel bei einer Blasenentz\u00fcndung f\u00fcr Schwangere"}]},{"@type":"WebSite","@id":"https:\/\/www.elternforen.com\/Blog\/#website","url":"https:\/\/www.elternforen.com\/Blog\/","name":"elternforen.com - Ratgeber-Magazin","description":"Der Blog \u00fcber Familie, Schwangerschaft, Babys und Kinder","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.elternforen.com\/Blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.elternforen.com\/Blog\/#\/schema\/person\/ed54c95f56854d06c00044b7c064dfba","name":"Redaktion","url":"https:\/\/www.elternforen.com\/Blog\/author\/redaktion\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.elternforen.com\/Blog\/wp-content\/uploads\/2013\/02\/woman-3186730_1920.jpg","_links":{"self":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts\/989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/comments?post=989"}],"version-history":[{"count":6,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts\/989\/revisions"}],"predecessor-version":[{"id":9231,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/posts\/989\/revisions\/9231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/media\/9180"}],"wp:attachment":[{"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/media?parent=989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/categories?post=989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.elternforen.com\/Blog\/wp-json\/wp\/v2\/tags?post=989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}